{"id":51236,"date":"2026-05-25T12:59:53","date_gmt":"2026-05-25T10:59:53","guid":{"rendered":"https:\/\/uecornella.cat\/?p=51236"},"modified":"2026-06-01T14:32:06","modified_gmt":"2026-06-01T12:32:06","slug":"ue-cornella-1-2-cf-vilanova-playoff","status":"publish","type":"post","link":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/","title":{"rendered":"UE CORNELL\u00c0 1-2 CF VILANOVA (PLAYOFF)"},"content":{"rendered":"<p>Sacrificio con recompensa final.<br \/>\n<!--more--><\/p>\n<p><span id=\"more-51001\"><\/span>El Cornell\u00e0 estar\u00e1 presente en la segunda eliminatoria del playoff de ascenso a Segunda Federaci\u00f3n despu\u00e9s de tumbar al CF Vilanova por el valor clasificatorio, y que premi\u00f3 a los nuestros con el empate global de ambos partidos.<\/p>\n<p>Con el buen resultado de la ida, los verdes salieron con ganas de encarrilar el pase a la siguiente ronda y no tardaron en dar muestra de ello; Santi Guzm\u00e1n y Marc Fern\u00e1ndez estuvieron cerca de abrir el marcador. Minutos despu\u00e9s, cerca del descanso, Isaac Vila estuvo acertado en una oportunidad visitante. Sin goles acab\u00f3 el primer tiempo.<\/p>\n<p>En la segunda mitad, el Vilanova avis\u00f3 con un bal\u00f3n al poste y acto seguido se adelant\u00f3 en el marcador, forzando una pr\u00f3rroga que el Cornell\u00e0 tuvo que afrontar en inferioridad por la expulsi\u00f3n de Ot Serrano.<\/p>\n<p>El tiempo extra arranc\u00f3 con un segundo gol para los visitantes, que dejaba fuera del playoff a los nuestros, pero la perseverancia y la ambici\u00f3n hizo que, lejos de rendirse, marcaran en el minuto 114 con un remate de Alejandro Pereira tras recibir un buen bal\u00f3n a\u00e9reo de Bruno Lorente.<\/p>\n<p>Un gol que desat\u00f3 la locura en el estadio, con una afici\u00f3n entregada y que ayud\u00f3 a su equipo a superar el primer objetivo. \u00c9pico.<\/p>\n<p>El pr\u00f3ximo fin de semana en Cornell\u00e0, partido de ida de la segunda eliminatoria contra el CF Badalona (domingo, 18:15h).<\/p>\n<ul>\n<li>Declaraciones post-partido de Ignasi Senabre:\u00a0<a href=\"https:\/\/x.com\/ue_cornella\/status\/2058620372765855928?s=20\">CLIC AQU\u00cd<\/a><\/li>\n<\/ul>\n<p><strong>FICHA T\u00c9CNICA<\/strong><\/p>\n<p><em>Estadio<\/em>: Nou Municipal de Cornell\u00e0<\/p>\n<p><em>Competici\u00f3n<\/em>: Primera ronda playoff ascenso (vuelta)<\/p>\n<p><em>Goles<\/em>: 0-1 (Ravent\u00f3s, 59\u2032) \/ 0-2 (Pol, 92&#8242;) \/ 1-2 (Alejandro, 114&#8242;)<\/p>\n<p><em>\u00c1rbitro<\/em>: Paul\u00ed Teruel Soler. TA a Tom\u00e1s, Marc e Isaac (UEC) \/ TA a Joan, Yahir y Pol (VIL) \/ TR a Ot (UEC).<\/p>\n<p><strong>UE CORNELL\u00c0<\/strong>: Isaac, Gerard (Manel, 46&#8242;), Tom\u00e1s (Moha, 71&#8242;), Ot, Marc Esteban, Aliaga, Marc Fdez., Santi (Leo, 65&#8242;), D\u00eddac (Alejandro, 85&#8242;), Bruno y Stefan (Tejada, 85&#8242;).<\/p>\n<p><strong>CF VILANOVA<\/strong>: Alex, Grima, Semur, Frutos (Castell, 104&#8242;), Derek, Sarsadenas (Gimeno, 55&#8242;), Albert, Guillem (Torrents, 55&#8242;), Yahir, Bocardo (Ravent\u00f3s, 46&#8242;) y Zourdine (Samba, 85&#8242;).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sacrificio con recompensa final.<\/p>\n","protected":false},"author":2247,"featured_media":51237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[156,162,161,138],"tags":[],"class_list":["post-51236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-actualidad-primer-equipo","category-cronica","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>UE CORNELL\u00c0 1-2 CF VILANOVA (PLAYOFF) - Uni\u00f3 Esportiva Cornell\u00e0<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UE CORNELL\u00c0 1-2 CF VILANOVA (PLAYOFF) - Uni\u00f3 Esportiva Cornell\u00e0\" \/>\n<meta property=\"og:description\" content=\"Sacrificio con recompensa final.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/\" \/>\n<meta property=\"og:site_name\" content=\"Uni\u00f3 Esportiva Cornell\u00e0\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UECornella?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-25T10:59:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T12:32:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uecornella.cat\/wp-content\/uploads\/2026\/05\/UEC-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alberto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ue_cornella\" \/>\n<meta name=\"twitter:site\" content=\"@ue_cornella\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alberto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/\"},\"author\":{\"name\":\"Alberto\",\"@id\":\"https:\/\/uecornella.cat\/en\/#\/schema\/person\/5461e8f6546c2aafc59aac7506719819\"},\"headline\":\"UE CORNELL\u00c0 1-2 CF VILANOVA (PLAYOFF)\",\"datePublished\":\"2026-05-25T10:59:53+00:00\",\"dateModified\":\"2026-06-01T12:32:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/\"},\"wordCount\":346,\"publisher\":{\"@id\":\"https:\/\/uecornella.cat\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/uecornella.cat\/wp-content\/uploads\/2026\/05\/UEC-.jpeg\",\"articleSection\":[\"Actualidad\",\"Actualidad Primer Equipo\",\"Cr\u00f3nica\",\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/\",\"url\":\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/\",\"name\":\"UE CORNELL\u00c0 1-2 CF VILANOVA (PLAYOFF) - Uni\u00f3 Esportiva Cornell\u00e0\",\"isPartOf\":{\"@id\":\"https:\/\/uecornella.cat\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/uecornella.cat\/wp-content\/uploads\/2026\/05\/UEC-.jpeg\",\"datePublished\":\"2026-05-25T10:59:53+00:00\",\"dateModified\":\"2026-06-01T12:32:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#primaryimage\",\"url\":\"https:\/\/uecornella.cat\/wp-content\/uploads\/2026\/05\/UEC-.jpeg\",\"contentUrl\":\"https:\/\/uecornella.cat\/wp-content\/uploads\/2026\/05\/UEC-.jpeg\",\"width\":1600,\"height\":1340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/uecornella.cat\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UE CORNELL\u00c0 1-2 CF VILANOVA (PLAYOFF)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/uecornella.cat\/en\/#website\",\"url\":\"https:\/\/uecornella.cat\/en\/\",\"name\":\"Uni\u00f3 Esportiva Cornell\u00e0\",\"description\":\"Escuela de f\u00fatbol y club de f\u00fatbol de Cornell\u00e0\",\"publisher\":{\"@id\":\"https:\/\/uecornella.cat\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/uecornella.cat\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/uecornella.cat\/en\/#organization\",\"name\":\"Uni\u00f3 Esportiva Cornell\u00e0\",\"url\":\"https:\/\/uecornella.cat\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/uecornella.cat\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.uecornella.cat\/wp-content\/uploads\/2022\/01\/apple-icon-144x144-1.png\",\"contentUrl\":\"https:\/\/www.uecornella.cat\/wp-content\/uploads\/2022\/01\/apple-icon-144x144-1.png\",\"width\":144,\"height\":144,\"caption\":\"Uni\u00f3 Esportiva Cornell\u00e0\"},\"image\":{\"@id\":\"https:\/\/uecornella.cat\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/UECornella?fref=ts\",\"https:\/\/x.com\/ue_cornella\",\"http:\/\/instagram.com\/uecornella\",\"https:\/\/www.youtube.com\/channel\/UCcwgya5MdVvxRn_MeD6A0vg\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/uecornella.cat\/en\/#\/schema\/person\/5461e8f6546c2aafc59aac7506719819\",\"name\":\"Alberto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/uecornella.cat\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/88cfb9cc05859e9f98fa45660f166e399532063623ab81b81f88226ac9333f8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/88cfb9cc05859e9f98fa45660f166e399532063623ab81b81f88226ac9333f8f?s=96&d=mm&r=g\",\"caption\":\"Alberto\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UE CORNELL\u00c0 1-2 CF VILANOVA (PLAYOFF) - Uni\u00f3 Esportiva Cornell\u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/","og_locale":"en_US","og_type":"article","og_title":"UE CORNELL\u00c0 1-2 CF VILANOVA (PLAYOFF) - Uni\u00f3 Esportiva Cornell\u00e0","og_description":"Sacrificio con recompensa final.","og_url":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/","og_site_name":"Uni\u00f3 Esportiva Cornell\u00e0","article_publisher":"https:\/\/www.facebook.com\/UECornella?fref=ts","article_published_time":"2026-05-25T10:59:53+00:00","article_modified_time":"2026-06-01T12:32:06+00:00","og_image":[{"width":1600,"height":1340,"url":"https:\/\/uecornella.cat\/wp-content\/uploads\/2026\/05\/UEC-.jpeg","type":"image\/jpeg"}],"author":"Alberto","twitter_card":"summary_large_image","twitter_creator":"@ue_cornella","twitter_site":"@ue_cornella","twitter_misc":{"Written by":"Alberto","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#article","isPartOf":{"@id":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/"},"author":{"name":"Alberto","@id":"https:\/\/uecornella.cat\/en\/#\/schema\/person\/5461e8f6546c2aafc59aac7506719819"},"headline":"UE CORNELL\u00c0 1-2 CF VILANOVA (PLAYOFF)","datePublished":"2026-05-25T10:59:53+00:00","dateModified":"2026-06-01T12:32:06+00:00","mainEntityOfPage":{"@id":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/"},"wordCount":346,"publisher":{"@id":"https:\/\/uecornella.cat\/en\/#organization"},"image":{"@id":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#primaryimage"},"thumbnailUrl":"https:\/\/uecornella.cat\/wp-content\/uploads\/2026\/05\/UEC-.jpeg","articleSection":["Actualidad","Actualidad Primer Equipo","Cr\u00f3nica","Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/","url":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/","name":"UE CORNELL\u00c0 1-2 CF VILANOVA (PLAYOFF) - Uni\u00f3 Esportiva Cornell\u00e0","isPartOf":{"@id":"https:\/\/uecornella.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#primaryimage"},"image":{"@id":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#primaryimage"},"thumbnailUrl":"https:\/\/uecornella.cat\/wp-content\/uploads\/2026\/05\/UEC-.jpeg","datePublished":"2026-05-25T10:59:53+00:00","dateModified":"2026-06-01T12:32:06+00:00","breadcrumb":{"@id":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#primaryimage","url":"https:\/\/uecornella.cat\/wp-content\/uploads\/2026\/05\/UEC-.jpeg","contentUrl":"https:\/\/uecornella.cat\/wp-content\/uploads\/2026\/05\/UEC-.jpeg","width":1600,"height":1340},{"@type":"BreadcrumbList","@id":"https:\/\/uecornella.cat\/en\/ue-cornella-1-2-cf-vilanova-playoff\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/uecornella.cat\/en\/"},{"@type":"ListItem","position":2,"name":"UE CORNELL\u00c0 1-2 CF VILANOVA (PLAYOFF)"}]},{"@type":"WebSite","@id":"https:\/\/uecornella.cat\/en\/#website","url":"https:\/\/uecornella.cat\/en\/","name":"Uni\u00f3 Esportiva Cornell\u00e0","description":"Escuela de f\u00fatbol y club de f\u00fatbol de Cornell\u00e0","publisher":{"@id":"https:\/\/uecornella.cat\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uecornella.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/uecornella.cat\/en\/#organization","name":"Uni\u00f3 Esportiva Cornell\u00e0","url":"https:\/\/uecornella.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uecornella.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.uecornella.cat\/wp-content\/uploads\/2022\/01\/apple-icon-144x144-1.png","contentUrl":"https:\/\/www.uecornella.cat\/wp-content\/uploads\/2022\/01\/apple-icon-144x144-1.png","width":144,"height":144,"caption":"Uni\u00f3 Esportiva Cornell\u00e0"},"image":{"@id":"https:\/\/uecornella.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UECornella?fref=ts","https:\/\/x.com\/ue_cornella","http:\/\/instagram.com\/uecornella","https:\/\/www.youtube.com\/channel\/UCcwgya5MdVvxRn_MeD6A0vg"]},{"@type":"Person","@id":"https:\/\/uecornella.cat\/en\/#\/schema\/person\/5461e8f6546c2aafc59aac7506719819","name":"Alberto","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uecornella.cat\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/88cfb9cc05859e9f98fa45660f166e399532063623ab81b81f88226ac9333f8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88cfb9cc05859e9f98fa45660f166e399532063623ab81b81f88226ac9333f8f?s=96&d=mm&r=g","caption":"Alberto"}}]}},"_links":{"self":[{"href":"https:\/\/uecornella.cat\/en\/wp-json\/wp\/v2\/posts\/51236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uecornella.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uecornella.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uecornella.cat\/en\/wp-json\/wp\/v2\/users\/2247"}],"replies":[{"embeddable":true,"href":"https:\/\/uecornella.cat\/en\/wp-json\/wp\/v2\/comments?post=51236"}],"version-history":[{"count":3,"href":"https:\/\/uecornella.cat\/en\/wp-json\/wp\/v2\/posts\/51236\/revisions"}],"predecessor-version":[{"id":51320,"href":"https:\/\/uecornella.cat\/en\/wp-json\/wp\/v2\/posts\/51236\/revisions\/51320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uecornella.cat\/en\/wp-json\/wp\/v2\/media\/51237"}],"wp:attachment":[{"href":"https:\/\/uecornella.cat\/en\/wp-json\/wp\/v2\/media?parent=51236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uecornella.cat\/en\/wp-json\/wp\/v2\/categories?post=51236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uecornella.cat\/en\/wp-json\/wp\/v2\/tags?post=51236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}